{"id":66295,"date":"2026-07-15T11:33:55","date_gmt":"2026-07-15T14:33:55","guid":{"rendered":"https:\/\/www.sincomam.org.br\/?p=66295"},"modified":"2026-07-15T11:33:55","modified_gmt":"2026-07-15T14:33:55","slug":"petrobras-adia-licitacao-para-construcao-do-fpso-de-buzios-12-2","status":"publish","type":"post","link":"https:\/\/www.sincomam.org.br\/index.php\/petrobras-adia-licitacao-para-construcao-do-fpso-de-buzios-12-2\/","title":{"rendered":"Petrobras adia licita\u00e7\u00e3o para constru\u00e7\u00e3o do FPSO de B\u00fazios 12"},"content":{"rendered":"<p><span dir=\"auto\">A Petrobras adiou por 180 dias o prazo de entrega de propostas da licita\u00e7\u00e3o do FPSO do projeto B\u00fazios 12, a P-91.\u00a0\u00a0<\/span><strong><span dir=\"auto\">At\u00e9 ent\u00e3o, o prazo era 9 de setembro deste ano<\/span><\/strong><span dir=\"auto\">\u00a0. Agora, os fornecedores interessados \u200b\u200bt\u00eam mais tempo para preparar as ofertas, ou que, acredita a Petrobras, tendem a aumentar a concorr\u00eancia da licita\u00e7\u00e3o.<\/span><\/p>\n<p><span dir=\"auto\">A petrol\u00edfera optou por ampliar o prazo porque entende que muitos dos fornecedores tamb\u00e9m participam da licita\u00e7\u00e3o para construir o FPSO de Albacora. Tendo mais tempo, os licitantes se dedicaram \u00e0s duas concorr\u00eancias.<\/span><\/p>\n<p><span dir=\"auto\">Al\u00e9m disso, pesou o fato de estar apostando em um processo de qualifica\u00e7\u00e3o de uma nova turbina chinesa, de maior pot\u00eancia, que poder\u00e1 fazer diferen\u00e7a no projeto. O equipamento est\u00e1 em fase final de certifica\u00e7\u00e3o e, acredita-se, caso seja usado, tem potencial para reduzir o pre\u00e7o e antecipar o prazo de entrega do FPSO em um ano.<\/span><\/p>\n<p><span dir=\"auto\">B\u00fazios 12 ser\u00e1 um\u00a0\u00a0<\/span><em><span dir=\"auto\">hub<\/span><\/em><span dir=\"auto\">\u00a0\u00a0para exporta\u00e7\u00e3o de g\u00e1s produzido no campo de B\u00fazios, no pr\u00e9-sal da Bacia de Santos. Al\u00e9m de contar com sistemas para processar e separar a produ\u00e7\u00e3o pr\u00f3pria, a unidade tamb\u00e9m ser\u00e1 capaz de exportar o g\u00e1s produzido em outras plataformas do campo que n\u00e3o foram originalmente projetadas para exporta\u00e7\u00e3o de g\u00e1s.<\/span><\/p>\n<p><span dir=\"auto\">A solu\u00e7\u00e3o foi idealizada para garantir o aproveitamento do g\u00e1s de B\u00fazios e a expans\u00e3o da oferta de g\u00e1s natural ao mercado brasileiro. O g\u00e1s escoado ser\u00e1 direcionado ao Complexo de Energias Boaventura, em Itabora\u00ed (RJ), por meio do gasoduto Rota 3 at\u00e9 a chegada \u00e0 costa.<\/span><\/p>\n<p><span dir=\"auto\">A plataforma ser\u00e1 interligada a 16 po\u00e7os \u2013 8 produtores e 8 injetores alternados de \u00e1gua e g\u00e1s -, com capacidade para produzir 180 mil barris de petr\u00f3leo por dia e 12 milh\u00f5es de m\u00b3\/dia de g\u00e1s natural.<\/span><\/p>\n<p><span dir=\"auto\">Fonte:\u00a0<\/span><span dir=\"auto\">Brasil Energia<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Petrobras adiou por 180 dias o prazo de entrega de propostas da licita\u00e7\u00e3o do FPSO do projeto B\u00fazios 12, a P-91.\u00a0\u00a0At\u00e9 ent\u00e3o, o prazo&#8230;<\/p>\n","protected":false},"author":1527,"featured_media":66296,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-66295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.sincomam.org.br\/index.php\/wp-json\/wp\/v2\/posts\/66295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sincomam.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sincomam.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sincomam.org.br\/index.php\/wp-json\/wp\/v2\/users\/1527"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sincomam.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=66295"}],"version-history":[{"count":1,"href":"https:\/\/www.sincomam.org.br\/index.php\/wp-json\/wp\/v2\/posts\/66295\/revisions"}],"predecessor-version":[{"id":66297,"href":"https:\/\/www.sincomam.org.br\/index.php\/wp-json\/wp\/v2\/posts\/66295\/revisions\/66297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sincomam.org.br\/index.php\/wp-json\/wp\/v2\/media\/66296"}],"wp:attachment":[{"href":"https:\/\/www.sincomam.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=66295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sincomam.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=66295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sincomam.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=66295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}